{"id":11335,"date":"2016-02-29T09:19:54","date_gmt":"2016-02-29T07:19:54","guid":{"rendered":"http:\/\/amasra.com.tr\/wp-content\/uploads\/2013\/05\/gokhan-ozen-amasra-6.jpg"},"modified":"2018-06-21T16:07:48","modified_gmt":"2018-06-21T13:07:48","slug":"gokhan-ozen-amasra-6","status":"inherit","type":"attachment","link":"https:\/\/amasra.com.tr\/en\/gokhan-ozen-amasra-6\/","title":{"rendered":"gokhan-ozen-amasra-6"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-11335","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/amasra.com.tr\/wp-content\/uploads\/2013\/05\/gokhan-ozen-amasra-6.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"230\" height=\"230\" src=\"https:\/\/amasra.com.tr\/wp-content\/uploads\/2013\/05\/gokhan-ozen-amasra-6-230x230.jpg\" class=\"attachment-medium size-medium\" alt=\"gokhan-ozen-amasra-6\" srcset=\"https:\/\/amasra.com.tr\/wp-content\/uploads\/2013\/05\/gokhan-ozen-amasra-6-230x230.jpg 230w, https:\/\/amasra.com.tr\/wp-content\/uploads\/2013\/05\/gokhan-ozen-amasra-6-167x167.jpg 167w, https:\/\/amasra.com.tr\/wp-content\/uploads\/2013\/05\/gokhan-ozen-amasra-6-50x50.jpg 50w\" sizes=\"auto, (max-width: 230px) 100vw, 230px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"gokhan-ozen-amasra-6","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":750,"height":500,"file":"2013\/05\/gokhan-ozen-amasra-6.jpg","sizes":{"thumbnail":{"file":"gokhan-ozen-amasra-6-167x167.jpg","width":167,"height":167,"mime_type":"image\/jpeg","source_url":"https:\/\/amasra.com.tr\/wp-content\/uploads\/2013\/05\/gokhan-ozen-amasra-6-167x167.jpg"},"large":{"file":"gokhan-ozen-amasra-6-350x233.jpg","width":350,"height":233,"mime_type":"image\/jpeg","source_url":"https:\/\/amasra.com.tr\/wp-content\/uploads\/2013\/05\/gokhan-ozen-amasra-6-350x233.jpg"},"post-thumbnail":{"file":"gokhan-ozen-amasra-6-167x111.jpg","width":167,"height":111,"mime_type":"image\/jpeg","source_url":"https:\/\/amasra.com.tr\/wp-content\/uploads\/2013\/05\/gokhan-ozen-amasra-6-167x111.jpg"},"sow-carousel-default":{"file":"gokhan-ozen-amasra-6-272x182.jpg","width":272,"height":182,"mime_type":"image\/jpeg","source_url":"https:\/\/amasra.com.tr\/wp-content\/uploads\/2013\/05\/gokhan-ozen-amasra-6-272x182.jpg"},"medium":{"file":"gokhan-ozen-amasra-6-230x230.jpg","width":230,"height":230,"mime_type":"image\/jpeg","source_url":"https:\/\/amasra.com.tr\/wp-content\/uploads\/2013\/05\/gokhan-ozen-amasra-6-230x230.jpg"},"thumbnail_old_50x50":{"file":"gokhan-ozen-amasra-6-50x50.jpg","width":50,"height":50,"mime_type":"image\/jpeg","source_url":"https:\/\/amasra.com.tr\/wp-content\/uploads\/2013\/05\/gokhan-ozen-amasra-6-50x50.jpg"},"owl_widget":{"file":"gokhan-ozen-amasra-6-180x100.jpg","width":180,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/amasra.com.tr\/wp-content\/uploads\/2013\/05\/gokhan-ozen-amasra-6-180x100.jpg"},"owl_function":{"file":"gokhan-ozen-amasra-6-600x280.jpg","width":600,"height":280,"mime_type":"image\/jpeg","source_url":"https:\/\/amasra.com.tr\/wp-content\/uploads\/2013\/05\/gokhan-ozen-amasra-6-600x280.jpg"},"full":{"file":"gokhan-ozen-amasra-6.jpg","width":750,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/amasra.com.tr\/wp-content\/uploads\/2013\/05\/gokhan-ozen-amasra-6.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"KemalOnurOzman","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/amasra.com.tr\/wp-content\/uploads\/2013\/05\/gokhan-ozen-amasra-6.jpg","_links":{"self":[{"href":"https:\/\/amasra.com.tr\/en\/wp-json\/wp\/v2\/media\/11335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amasra.com.tr\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/amasra.com.tr\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/amasra.com.tr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amasra.com.tr\/en\/wp-json\/wp\/v2\/comments?post=11335"}]}}