{"id":14547,"date":"2018-09-05T20:08:02","date_gmt":"2018-09-05T17:08:02","guid":{"rendered":"http:\/\/amasra.com.tr\/wp-content\/uploads\/2018\/09\/amasra-balik-fiyatlari-2018.jpg"},"modified":"2018-09-05T20:08:02","modified_gmt":"2018-09-05T17:08:02","slug":"precios-del-pescado-amasra-2018","status":"inherit","type":"attachment","link":"https:\/\/amasra.com.tr\/es\/amasra-balik-fiyatlari-2\/amasra-balik-fiyatlari-2018\/","title":{"rendered":"amasra-fish-prices-2018"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-14547","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/amasra.com.tr\/wp-content\/uploads\/2018\/09\/amasra-balik-fiyatlari-2018.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"230\" height=\"230\" src=\"https:\/\/amasra.com.tr\/wp-content\/uploads\/2018\/09\/amasra-balik-fiyatlari-2018-230x230.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/amasra.com.tr\/wp-content\/uploads\/2018\/09\/amasra-balik-fiyatlari-2018-230x230.jpg 230w, https:\/\/amasra.com.tr\/wp-content\/uploads\/2018\/09\/amasra-balik-fiyatlari-2018-167x167.jpg 167w\" sizes=\"auto, (max-width: 230px) 100vw, 230px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":900,"height":1200,"file":"2018\/09\/amasra-balik-fiyatlari-2018.jpg","sizes":{"thumbnail":{"file":"amasra-balik-fiyatlari-2018-167x167.jpg","width":167,"height":167,"mime_type":"image\/jpeg","source_url":"https:\/\/amasra.com.tr\/wp-content\/uploads\/2018\/09\/amasra-balik-fiyatlari-2018-167x167.jpg"},"medium":{"file":"amasra-balik-fiyatlari-2018-230x230.jpg","width":230,"height":230,"mime_type":"image\/jpeg","source_url":"https:\/\/amasra.com.tr\/wp-content\/uploads\/2018\/09\/amasra-balik-fiyatlari-2018-230x230.jpg"},"medium_large":{"file":"amasra-balik-fiyatlari-2018-768x1024.jpg","width":768,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/amasra.com.tr\/wp-content\/uploads\/2018\/09\/amasra-balik-fiyatlari-2018-768x1024.jpg"},"large":{"file":"amasra-balik-fiyatlari-2018-263x350.jpg","width":263,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/amasra.com.tr\/wp-content\/uploads\/2018\/09\/amasra-balik-fiyatlari-2018-263x350.jpg"},"post-thumbnail":{"file":"amasra-balik-fiyatlari-2018-125x167.jpg","width":125,"height":167,"mime_type":"image\/jpeg","source_url":"https:\/\/amasra.com.tr\/wp-content\/uploads\/2018\/09\/amasra-balik-fiyatlari-2018-125x167.jpg"},"sow-carousel-default":{"file":"amasra-balik-fiyatlari-2018-272x182.jpg","width":272,"height":182,"mime_type":"image\/jpeg","source_url":"https:\/\/amasra.com.tr\/wp-content\/uploads\/2018\/09\/amasra-balik-fiyatlari-2018-272x182.jpg"},"full":{"file":"amasra-balik-fiyatlari-2018.jpg","width":900,"height":1200,"mime_type":"image\/jpeg","source_url":"https:\/\/amasra.com.tr\/wp-content\/uploads\/2018\/09\/amasra-balik-fiyatlari-2018.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"1536174056","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":14543,"source_url":"https:\/\/amasra.com.tr\/wp-content\/uploads\/2018\/09\/amasra-balik-fiyatlari-2018.jpg","_links":{"self":[{"href":"https:\/\/amasra.com.tr\/es\/wp-json\/wp\/v2\/media\/14547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amasra.com.tr\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/amasra.com.tr\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/amasra.com.tr\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amasra.com.tr\/es\/wp-json\/wp\/v2\/comments?post=14547"}]}}